{"id":11015,"date":"2021-08-12T11:54:35","date_gmt":"2021-08-12T09:54:35","guid":{"rendered":"https:\/\/www.radio19.it\/?p=11015"},"modified":"2021-08-23T13:36:41","modified_gmt":"2021-08-23T11:36:41","slug":"uscimmo-a-riveder-le-stelle","status":"publish","type":"post","link":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/","title":{"rendered":"Uscimmo a riveder le stelle"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.10.3&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><em>&#8220;Uscimmo a riveder le stelle&#8221;<\/em><\/h2>\n<p>\u00e8 il titolo che unisce tre diversi eventi organizzati dall&#8217;Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico.<\/p>\n<p>Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione con la societ\u00e0 in-house Mediaterreaneo Servizi e l&#8217;Associazione Culturale il Sestante, <em>\u201cUscimmo a riveder le stelle\u201d<\/em> si terr\u00e0 nella verde cornice del Parco Mandela di Sestri Levante. Protagonista \u00e8 la storia di vita vissuta di due &#8220;camalli&#8221; del porto di Genova, diventati attori del cinema muto:\u00a0Bartolomeo Pagano, in arte Maciste, famosissimo e osannato dal pubblico ed Umberto Guarracino, in arte Cimaste, celebre invece per breve tempo, prima dell\u2019oblio. Li uniscono il lavoro e la fatica, li separano la carriera e l\u2019epilogo. Due destini diametralmente opposti, i loro, che si incroceranno per tre volte sul set.<\/p>\n<p><strong>&#8220;Maciste Vs Cimaste&#8221; <\/strong>\u00e8 un tuffo nel passato, con storie e legami unici e sorprendenti, \u00e8 un incontro di parole, musica e immagini che dagli albori del cinematografo arriva intatto fino ai giorni scorsi e ci svela qualcosa che potrebbe rivelarsi molto utile anche in futuro. Ci racconta la loro epopea, fra avventura e sventura, Massimo Minella, giornalista e scrittore, vicecaporedattore della redazione genovese de La Repubblica, in scena insieme a Franco Piccolo (fisarmonica) e Augusto Forin (chitarra e voce).<\/p>\n<p>A seguire, l&#8217;osservazione degli astri principali del cielo estivo con la guida dagli esperti dell&#8217;Associazione Culturale il Sestante. Per tornare a riveder le stelle.<\/p>\n<p>Dichiara il Professore Fabrizio Benente, Prorettore alla Terza missione UniGe: &lt;&lt;\u201c<em>Uscimmo a riveder le stelle\u201d prende l\u2019avvio con l\u2019appuntamento di Sestri Levante, realizzato in collaborazione con il Comune e con l\u2019Associazione culturale il Sestante. Il titolo non contiene solo un evidente richiamo dantesco, ma \u00e8 anche un auspicio che \u00e8 sicuramente condivisibile da tutti noi. L\u2019estate 2021 trascorre, infatti, in attesa del sospirato ritorno alla normalit\u00e0 dell\u2019attivit\u00e0 didattica e di ricerca \u201cin presenza\u201d. Il ruolo dell\u2019Ateneo, e propriamente della Terza missione, \u00e8 quello di contribuire a costruire percorsi di cultura e divulgazione anche fuori dai Palazzi e dalle aule dell\u2019Universit\u00e0, trovando la collaborazione delle amministrazioni comunali, delle associazioni e dei principali attori delle attivit\u00e0 culturali della Liguria. Un mio particolare ringraziamento deve andare a Maria Elisio Bixio, al Comune di Sestri Levante, nonch\u00e9 a tutto il personale del Settore eventi e comunicazione interna dell\u2019Universit\u00e0 di Genova.&gt;&gt;<\/em><\/p>\n<p>L&#8217;iniziativa \u00e8 a ingresso gratuito con prenotazione obbligatoria nella sezione eventi del portale turistico <a href=\"http:\/\/www.sestri-levante.net\/\">www.sestri-levante.net<\/a>.<\/p>\n<p>Per la partecipazione all\u2019evento \u00e8 obbligatorio il possesso di Green pass.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Uscimmo a riveder le stelle&#8221; \u00e8 il titolo che unisce tre diversi eventi organizzati dall&#8217;Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<h2><em>\"Uscimmo a riveder le stelle\"<\/em><\/h2>\r\n\u00e8 il titolo che unisce tre diversi eventi organizzati dall'Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico.\r\n\r\nGioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione con la societ\u00e0 in-house Mediaterreaneo Servizi e l'Associazione Culturale il Sestante, <em>\u201cUscimmo a riveder le stelle\u201d<\/em> si terr\u00e0 nella verde cornice del Parco Mandela di Sestri Levante. Protagonista \u00e8 la storia di vita vissuta di due \"camalli\" del porto di Genova, diventati attori del cinema muto:\u00a0Bartolomeo Pagano, in arte Maciste, famosissimo e osannato dal pubblico ed Umberto Guarracino, in arte Cimaste, celebre invece per breve tempo, prima dell\u2019oblio. Li uniscono il lavoro e la fatica, li separano la carriera e l\u2019epilogo. Due destini diametralmente opposti, i loro, che si incroceranno per tre volte sul set.\r\n\r\n<strong>\"Maciste Vs Cimaste\" <\/strong>\u00e8 un tuffo nel passato, con storie e legami unici e sorprendenti, \u00e8 un incontro di parole, musica e immagini che dagli albori del cinematografo arriva intatto fino ai giorni scorsi e ci svela qualcosa che potrebbe rivelarsi molto utile anche in futuro. Ci racconta la loro epopea, fra avventura e sventura, Massimo Minella, giornalista e scrittore, vicecaporedattore della redazione genovese de La Repubblica, in scena insieme a Franco Piccolo (fisarmonica) e Augusto Forin (chitarra e voce).\r\n\r\nA seguire, l'osservazione degli astri principali del cielo estivo con la guida dagli esperti dell'Associazione Culturale il Sestante. Per tornare a riveder le stelle.\r\n\r\nDichiara il Professore Fabrizio Benente, Prorettore alla Terza missione UniGe: <<\u201c<em>Uscimmo a riveder le stelle\u201d prende l\u2019avvio con l\u2019appuntamento di Sestri Levante, realizzato in collaborazione con il Comune e con l\u2019Associazione culturale il Sestante. Il titolo non contiene solo un evidente richiamo dantesco, ma \u00e8 anche un auspicio che \u00e8 sicuramente condivisibile da tutti noi. L\u2019estate 2021 trascorre, infatti, in attesa del sospirato ritorno alla normalit\u00e0 dell\u2019attivit\u00e0 didattica e di ricerca \u201cin presenza\u201d. Il ruolo dell\u2019Ateneo, e propriamente della Terza missione, \u00e8 quello di contribuire a costruire percorsi di cultura e divulgazione anche fuori dai Palazzi e dalle aule dell\u2019Universit\u00e0, trovando la collaborazione delle amministrazioni comunali, delle associazioni e dei principali attori delle attivit\u00e0 culturali della Liguria. Un mio particolare ringraziamento deve andare a Maria Elisio Bixio, al Comune di Sestri Levante, nonch\u00e9 a tutto il personale del Settore eventi e comunicazione interna dell\u2019Universit\u00e0 di Genova.>><\/em>\r\n\r\nL'iniziativa \u00e8 a ingresso gratuito con prenotazione obbligatoria nella sezione eventi del portale turistico <a href=\"http:\/\/www.sestri-levante.net\/\">www.sestri-levante.net<\/a>.\r\n\r\nPer la partecipazione all\u2019evento \u00e8 obbligatorio il possesso di Green pass.","_et_gb_content_width":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-11015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Radio19\"\/>\n\t<meta name=\"google-site-verification\" content=\"_5_UJYEzkwV4P-tW6QOxlWBK1j5WbW9SVu1gZOXojMY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Radio19\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Radio19 | Uscimmo a riveder le stelle\" \/>\n\t\t<meta property=\"og:description\" content=\"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"495\" \/>\n\t\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-12T09:54:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-23T11:36:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radio19\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Radio19Family\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Radio19 | Uscimmo a riveder le stelle\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#article\",\"name\":\"Radio19 | Uscimmo a riveder le stelle\",\"headline\":\"Uscimmo a riveder le stelle\",\"author\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/author\\\/ruggerosalvaneschi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/A-riveder-le-stelle-definitiva-1-e1629545785506.png\",\"width\":495,\"height\":700,\"caption\":\"Radio 19 - Uscimmo a riveder le stelle\"},\"datePublished\":\"2021-08-12T11:54:35+02:00\",\"dateModified\":\"2021-08-23T13:36:41+02:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#webpage\"},\"articleSection\":\"Eventi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.radio19.it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/category\\\/eventi\\\/#listItem\",\"name\":\"Eventi\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/category\\\/eventi\\\/#listItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/category\\\/eventi\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#listItem\",\"name\":\"Uscimmo a riveder le stelle\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#listItem\",\"position\":3,\"name\":\"Uscimmo a riveder le stelle\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/category\\\/eventi\\\/#listItem\",\"name\":\"Eventi\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/#organization\",\"name\":\"Radio 19 #PUREHITS\",\"description\":\"Radio19 #PUREHITS\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/\",\"telephone\":\"+39010546519\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-Radio-19-727x269-1-e1585917046850.png\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#organizationLogo\",\"width\":200,\"height\":74,\"caption\":\"Radio 19 #PUREHITS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/radio19_\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/author\\\/ruggerosalvaneschi\\\/#author\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/author\\\/ruggerosalvaneschi\\\/\",\"name\":\"Radio19\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b108e0721682f939fb0c394061cfb65ce5906d1915ed24b66248839d7e05847?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Radio19\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#webpage\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/\",\"name\":\"Radio19 | Uscimmo a riveder le stelle\",\"description\":\"\\u201cUscimmo a riveder le stelle\\u201d \\u00e8 il titolo che unisce tre diversi eventi organizzati dall\\u2019Universit\\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/author\\\/ruggerosalvaneschi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/author\\\/ruggerosalvaneschi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/A-riveder-le-stelle-definitiva-1-e1629545785506.png\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#mainImage\",\"width\":495,\"height\":700,\"caption\":\"Radio 19 - Uscimmo a riveder le stelle\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/index.php\\\/uscimmo-a-riveder-le-stelle\\\/#mainImage\"},\"datePublished\":\"2021-08-12T11:54:35+02:00\",\"dateModified\":\"2021-08-23T13:36:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.radio19.it\\\/#website\",\"url\":\"https:\\\/\\\/www.radio19.it\\\/\",\"name\":\"Radio19\",\"description\":\"Radio19 #PUREHITS\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.radio19.it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script type=\"text\/javascript\">\n\t\t\t(function(c,l,a,r,i,t,y){\n\t\t\tc[a]=c[a]||function(){(c[a].q=c[a].q||[]).push(arguments)};t=l.createElement(r);t.async=1;\n\t\t\tt.src=\"https:\/\/www.clarity.ms\/tag\/\"+i+\"?ref=aioseo\";y=l.getElementsByTagName(r)[0];y.parentNode.insertBefore(t,y);\n\t\t})(window, document, \"clarity\", \"script\", \"u7765ash9x\");\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Radio19 | Uscimmo a riveder le stelle","description":"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione","canonical_url":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"_5_UJYEzkwV4P-tW6QOxlWBK1j5WbW9SVu1gZOXojMY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#article","name":"Radio19 | Uscimmo a riveder le stelle","headline":"Uscimmo a riveder le stelle","author":{"@id":"https:\/\/www.radio19.it\/index.php\/author\/ruggerosalvaneschi\/#author"},"publisher":{"@id":"https:\/\/www.radio19.it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png","width":495,"height":700,"caption":"Radio 19 - Uscimmo a riveder le stelle"},"datePublished":"2021-08-12T11:54:35+02:00","dateModified":"2021-08-23T13:36:41+02:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#webpage"},"isPartOf":{"@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#webpage"},"articleSection":"Eventi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.radio19.it#listItem","position":1,"name":"Home","item":"https:\/\/www.radio19.it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.radio19.it\/index.php\/category\/eventi\/#listItem","name":"Eventi"}},{"@type":"ListItem","@id":"https:\/\/www.radio19.it\/index.php\/category\/eventi\/#listItem","position":2,"name":"Eventi","item":"https:\/\/www.radio19.it\/index.php\/category\/eventi\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#listItem","name":"Uscimmo a riveder le stelle"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.radio19.it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#listItem","position":3,"name":"Uscimmo a riveder le stelle","previousItem":{"@type":"ListItem","@id":"https:\/\/www.radio19.it\/index.php\/category\/eventi\/#listItem","name":"Eventi"}}]},{"@type":"Organization","@id":"https:\/\/www.radio19.it\/#organization","name":"Radio 19 #PUREHITS","description":"Radio19 #PUREHITS","url":"https:\/\/www.radio19.it\/","telephone":"+39010546519","logo":{"@type":"ImageObject","url":"https:\/\/www.radio19.it\/wp-content\/uploads\/2020\/03\/Logo-Radio-19-727x269-1-e1585917046850.png","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#organizationLogo","width":200,"height":74,"caption":"Radio 19 #PUREHITS"},"image":{"@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/radio19_\/"]},{"@type":"Person","@id":"https:\/\/www.radio19.it\/index.php\/author\/ruggerosalvaneschi\/#author","url":"https:\/\/www.radio19.it\/index.php\/author\/ruggerosalvaneschi\/","name":"Radio19","image":{"@type":"ImageObject","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3b108e0721682f939fb0c394061cfb65ce5906d1915ed24b66248839d7e05847?s=96&d=mm&r=g","width":96,"height":96,"caption":"Radio19"}},{"@type":"WebPage","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#webpage","url":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/","name":"Radio19 | Uscimmo a riveder le stelle","description":"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.radio19.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#breadcrumblist"},"author":{"@id":"https:\/\/www.radio19.it\/index.php\/author\/ruggerosalvaneschi\/#author"},"creator":{"@id":"https:\/\/www.radio19.it\/index.php\/author\/ruggerosalvaneschi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png","@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#mainImage","width":495,"height":700,"caption":"Radio 19 - Uscimmo a riveder le stelle"},"primaryImageOfPage":{"@id":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/#mainImage"},"datePublished":"2021-08-12T11:54:35+02:00","dateModified":"2021-08-23T13:36:41+02:00"},{"@type":"WebSite","@id":"https:\/\/www.radio19.it\/#website","url":"https:\/\/www.radio19.it\/","name":"Radio19","description":"Radio19 #PUREHITS","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.radio19.it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Radio19","og:type":"article","og:title":"Radio19 | Uscimmo a riveder le stelle","og:description":"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione","og:url":"https:\/\/www.radio19.it\/index.php\/uscimmo-a-riveder-le-stelle\/","og:image":"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png","og:image:secure_url":"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png","og:image:width":495,"og:image:height":700,"article:published_time":"2021-08-12T09:54:35+00:00","article:modified_time":"2021-08-23T11:36:41+00:00","article:publisher":"https:\/\/www.facebook.com\/radio19","twitter:card":"summary","twitter:site":"@Radio19Family","twitter:title":"Radio19 | Uscimmo a riveder le stelle","twitter:description":"\u201cUscimmo a riveder le stelle\u201d \u00e8 il titolo che unisce tre diversi eventi organizzati dall\u2019Universit\u00e0 di Genova in ville storiche e parchi pubblici della Liguria, per tornare a praticare la cultura sul territorio a diretto contatto con il pubblico. Gioved\u00ec 19 agosto, alle ore 21.15, promossa dal Comune di Sestri Levante e svolta in collaborazione","twitter:image":"https:\/\/www.radio19.it\/wp-content\/uploads\/2021\/08\/A-riveder-le-stelle-definitiva-1-e1629545785506.png"},"aioseo_meta_data":{"post_id":"11015","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"uscimmo a riveder le stelle","score":82,"analysis":{"keyphraseInTitle":{"title":"Focus Keyphrase in SEO title","description":"Focus Keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Focus Keyphrase in URL","description":"Focus Keyphrase used in the URL.","score":5,"maxScore":5,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Focus keyphrase is slightly long. Try to make it shorter.","score":6,"maxScore":9,"error":1,"length":5},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase does not appear in the first paragraph. Make sure the topic is clear immediately.","score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"title":"Focus Keyphrase in Subheadings","description":"Your H2 or H3 subheading reflects the topic of your copy. Good job!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[]}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-12 09:48:43","updated":"2025-06-04 00:35:39","seo_analyzer_scan_date":null,"focus_keyword":"uscimmo a riveder le stelle","additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/posts\/11015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/comments?post=11015"}],"version-history":[{"count":0,"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/posts\/11015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/media\/11017"}],"wp:attachment":[{"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/media?parent=11015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/categories?post=11015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radio19.it\/index.php\/wp-json\/wp\/v2\/tags?post=11015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}